{"id":3793,"count":3,"description":"","link":"https:\/\/swiatsupli.pl\/blog\/tag\/sterydy-anaboliczne\/","name":"sterydy anaboliczne","slug":"sterydy-anaboliczne","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>sterydy anaboliczne - Blog \u015awiat Supli<\/title>\n<meta name=\"description\" content=\"Blog \u015awiat Supli sterydy anaboliczne\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swiatsupli.pl\/blog\/tag\/sterydy-anaboliczne\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"sterydy anaboliczne - Blog \u015awiat Supli\" \/>\n<meta property=\"og:description\" content=\"Blog \u015awiat Supli sterydy anaboliczne\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swiatsupli.pl\/blog\/tag\/sterydy-anaboliczne\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog \u015awiat Supli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@SwiatSupli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/swiatsupli.pl\\\/blog\\\/tag\\\/sterydy-anaboliczne\\\/\",\"url\":\"https:\\\/\\\/swiatsupli.pl\\\/blog\\\/tag\\\/sterydy-anaboliczne\\\/\",\"name\":\"sterydy anaboliczne - Blog \u015awiat Supli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swiatsupli.pl\\\/blog\\\/#website\"},\"description\":\"Blog \u015awiat Supli sterydy anaboliczne\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swiatsupli.pl\\\/blog\\\/tag\\\/sterydy-anaboliczne\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swiatsupli.pl\\\/blog\\\/tag\\\/sterydy-anaboliczne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/swiatsupli.pl\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"sterydy anaboliczne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swiatsupli.pl\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/swiatsupli.pl\\\/blog\\\/\",\"name\":\"Blog \u015awiat Supli\",\"description\":\"Wspieramy Tw\u00f3j styl \u017cycia\",\"publisher\":{\"@id\":\"https:\\\/\\\/swiatsupli.pl\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swiatsupli.pl\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swiatsupli.pl\\\/blog\\\/#organization\",\"name\":\"\u015awiat Supli\",\"url\":\"https:\\\/\\\/swiatsupli.pl\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/swiatsupli.pl\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/swiatsupli.pl\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/swiat-supli-logo-hex-color-bg-2-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/swiatsupli.pl\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/swiat-supli-logo-hex-color-bg-2-scaled.jpg\",\"width\":2560,\"height\":680,\"caption\":\"\u015awiat Supli\"},\"image\":{\"@id\":\"https:\\\/\\\/swiatsupli.pl\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Swiat.Supli\",\"https:\\\/\\\/x.com\\\/SwiatSupli\",\"https:\\\/\\\/www.instagram.com\\\/swiatsupli_pl\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbrXSxhnVQmv08kapZgYW5Q\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"sterydy anaboliczne - Blog \u015awiat Supli","description":"Blog \u015awiat Supli sterydy anaboliczne","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swiatsupli.pl\/blog\/tag\/sterydy-anaboliczne\/","og_locale":"pl_PL","og_type":"article","og_title":"sterydy anaboliczne - Blog \u015awiat Supli","og_description":"Blog \u015awiat Supli sterydy anaboliczne","og_url":"https:\/\/swiatsupli.pl\/blog\/tag\/sterydy-anaboliczne\/","og_site_name":"Blog \u015awiat Supli","twitter_card":"summary_large_image","twitter_site":"@SwiatSupli","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/swiatsupli.pl\/blog\/tag\/sterydy-anaboliczne\/","url":"https:\/\/swiatsupli.pl\/blog\/tag\/sterydy-anaboliczne\/","name":"sterydy anaboliczne - Blog \u015awiat Supli","isPartOf":{"@id":"https:\/\/swiatsupli.pl\/blog\/#website"},"description":"Blog \u015awiat Supli sterydy anaboliczne","breadcrumb":{"@id":"https:\/\/swiatsupli.pl\/blog\/tag\/sterydy-anaboliczne\/#breadcrumb"},"inLanguage":"pl-PL"},{"@type":"BreadcrumbList","@id":"https:\/\/swiatsupli.pl\/blog\/tag\/sterydy-anaboliczne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/swiatsupli.pl\/blog\/"},{"@type":"ListItem","position":2,"name":"sterydy anaboliczne"}]},{"@type":"WebSite","@id":"https:\/\/swiatsupli.pl\/blog\/#website","url":"https:\/\/swiatsupli.pl\/blog\/","name":"Blog \u015awiat Supli","description":"Wspieramy Tw\u00f3j styl \u017cycia","publisher":{"@id":"https:\/\/swiatsupli.pl\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swiatsupli.pl\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/swiatsupli.pl\/blog\/#organization","name":"\u015awiat Supli","url":"https:\/\/swiatsupli.pl\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/swiatsupli.pl\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/swiatsupli.pl\/blog\/wp-content\/uploads\/2020\/10\/swiat-supli-logo-hex-color-bg-2-scaled.jpg","contentUrl":"https:\/\/swiatsupli.pl\/blog\/wp-content\/uploads\/2020\/10\/swiat-supli-logo-hex-color-bg-2-scaled.jpg","width":2560,"height":680,"caption":"\u015awiat Supli"},"image":{"@id":"https:\/\/swiatsupli.pl\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Swiat.Supli","https:\/\/x.com\/SwiatSupli","https:\/\/www.instagram.com\/swiatsupli_pl\/","https:\/\/www.youtube.com\/channel\/UCbrXSxhnVQmv08kapZgYW5Q"]}]}},"_links":{"self":[{"href":"https:\/\/swiatsupli.pl\/blog\/wp-json\/wp\/v2\/tags\/3793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swiatsupli.pl\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/swiatsupli.pl\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/swiatsupli.pl\/blog\/wp-json\/wp\/v2\/posts?tags=3793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}